{"id":91,"count":2,"description":"","link":"https:\/\/www.deeds.com\/articles\/category\/quiet-title-action\/","name":"Quiet Title Action","slug":"quiet-title-action","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quiet Title Action Archives - Deeds.com<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quiet Title Action Archives - Deeds.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deeds.com\/articles\/category\/quiet-title-action\/\" \/>\n<meta property=\"og:site_name\" content=\"Deeds.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@RealEstateDeeds\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.deeds.com\\\/articles\\\/category\\\/quiet-title-action\\\/\",\"url\":\"https:\\\/\\\/www.deeds.com\\\/articles\\\/category\\\/quiet-title-action\\\/\",\"name\":\"Quiet Title Action Archives - Deeds.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deeds.com\\\/articles\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deeds.com\\\/articles\\\/category\\\/quiet-title-action\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deeds.com\\\/articles\\\/category\\\/quiet-title-action\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.deeds.com\\\/articles\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quiet Title Action\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deeds.com\\\/articles\\\/#website\",\"url\":\"https:\\\/\\\/www.deeds.com\\\/articles\\\/\",\"name\":\"Deeds.com\",\"description\":\"Real Estate Deeds Made Easy Since 1997\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deeds.com\\\/articles\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deeds.com\\\/articles\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deeds.com\\\/articles\\\/#organization\",\"name\":\"Deeds.com\",\"url\":\"https:\\\/\\\/www.deeds.com\\\/articles\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.deeds.com\\\/articles\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deeds.com\\\/articles\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/deeds-logo-bw.png\",\"contentUrl\":\"https:\\\/\\\/www.deeds.com\\\/articles\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/deeds-logo-bw.png\",\"width\":417,\"height\":208,\"caption\":\"Deeds.com\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deeds.com\\\/articles\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/deedsrealestate\\\/\",\"https:\\\/\\\/x.com\\\/RealEstateDeeds\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCWGNKXWKH9nluFfeIvG0OTQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quiet Title Action Archives - Deeds.com","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Quiet Title Action Archives - Deeds.com","og_url":"https:\/\/www.deeds.com\/articles\/category\/quiet-title-action\/","og_site_name":"Deeds.com","twitter_card":"summary_large_image","twitter_site":"@RealEstateDeeds","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.deeds.com\/articles\/category\/quiet-title-action\/","url":"https:\/\/www.deeds.com\/articles\/category\/quiet-title-action\/","name":"Quiet Title Action Archives - Deeds.com","isPartOf":{"@id":"https:\/\/www.deeds.com\/articles\/#website"},"breadcrumb":{"@id":"https:\/\/www.deeds.com\/articles\/category\/quiet-title-action\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.deeds.com\/articles\/category\/quiet-title-action\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.deeds.com\/articles\/"},{"@type":"ListItem","position":2,"name":"Quiet Title Action"}]},{"@type":"WebSite","@id":"https:\/\/www.deeds.com\/articles\/#website","url":"https:\/\/www.deeds.com\/articles\/","name":"Deeds.com","description":"Real Estate Deeds Made Easy Since 1997","publisher":{"@id":"https:\/\/www.deeds.com\/articles\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deeds.com\/articles\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.deeds.com\/articles\/#organization","name":"Deeds.com","url":"https:\/\/www.deeds.com\/articles\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.deeds.com\/articles\/#\/schema\/logo\/image\/","url":"https:\/\/www.deeds.com\/articles\/wp-content\/uploads\/2018\/10\/deeds-logo-bw.png","contentUrl":"https:\/\/www.deeds.com\/articles\/wp-content\/uploads\/2018\/10\/deeds-logo-bw.png","width":417,"height":208,"caption":"Deeds.com"},"image":{"@id":"https:\/\/www.deeds.com\/articles\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/deedsrealestate\/","https:\/\/x.com\/RealEstateDeeds","https:\/\/www.youtube.com\/channel\/UCWGNKXWKH9nluFfeIvG0OTQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.deeds.com\/articles\/wp-json\/wp\/v2\/categories\/91","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deeds.com\/articles\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.deeds.com\/articles\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.deeds.com\/articles\/wp-json\/wp\/v2\/posts?categories=91"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}